{"id":8061,"count":4,"description":"","link":"https:\/\/demo.ews.pe\/dooplay\/director\/carolina-jimenez\/","name":"Carolina Jim\u00e9nez","slug":"carolina-jimenez","taxonomy":"dtdirector","meta":[],"_links":{"self":[{"href":"https:\/\/demo.ews.pe\/dooplay\/wp-json\/wp\/v2\/dtdirector\/8061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.ews.pe\/dooplay\/wp-json\/wp\/v2\/dtdirector"}],"about":[{"href":"https:\/\/demo.ews.pe\/dooplay\/wp-json\/wp\/v2\/taxonomies\/dtdirector"}],"wp:post_type":[{"href":"https:\/\/demo.ews.pe\/dooplay\/wp-json\/wp\/v2\/movies?dtdirector=8061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}